{"id":310,"date":"2023-02-20T14:39:56","date_gmt":"2023-02-20T13:39:56","guid":{"rendered":"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/?page_id=310"},"modified":"2023-02-20T14:59:14","modified_gmt":"2023-02-20T13:59:14","slug":"offerte","status":"publish","type":"page","link":"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/index.php\/offerte\/","title":{"rendered":"Offerte"},"content":{"rendered":"<p>[vc_row][vc_column][vc_raw_html el_class=&#8221;richiedinfo&#8221;]JTNDYSUyMGhyZWYlM0QlMjJtYWlsdG8lM0FpbmZvJTQwb2xpdmV0b3N1bGxhZ28uY29tJTIyJTNFJTBBUHJlbm90YSUzQyUyRmElM0U=[\/vc_raw_html][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;312&#8243; img_size=&#8221;600&#215;600&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h3><strong>Fuga per due<\/strong><\/h3>\n<p>Nel giorno pi\u00f9 romantico dell\u2019anno, la Country House Oliveto sul Lago \u00e8 la scelta perfetta per lasciarsi alle spalle la quotidianit\u00e0 per ritrovare l\u2019intesa di coppia. Immersi nella meravigliosa cornice dei colli bolognesi, potrete riprendervi il tempo per voi, tra natura e benessere.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<section id=\"sec-3525\" class=\"u-align-center u-clearfix u-section-4\">\n<div class=\"u-clearfix u-sheet u-sheet-1\">\n<p class=\"u-align-center u-custom-font u-font-playfair-display u-text u-text-custom-color-4 u-text-1\" style=\"text-align: center;\">L&#8217;esperienza include:<br \/>\nUn pernottamento per due persone<br \/>\nColazione con i prodotti della nostra azienda agricola<br \/>\nOmaggio bottiglia di vino Palazzo di Varignana in camera<\/p>\n<p class=\"u-align-center u-custom-font u-font-montserrat u-text u-text-custom-color-4 u-text-2\" style=\"text-align: center;\">Quotazione in camera matrimoniale Oliveto View o Garden View per una notte per due persone con colazione inclusa: 150 euro<\/p>\n<p style=\"text-align: center;\">Quotazione in camera matrimoniale Chiesina per una notte per due persone con colazione inclusa: 170 euro<\/p>\n<p style=\"text-align: center;\">Prenotazione obbligatoria a\u00a0<a class=\"u-active-none u-border-none u-btn u-button-link u-button-style u-hover-none u-none u-text-palette-1-base u-btn-1\" href=\"https:\/\/nicepage.cloud\/\">info@olivetosullago.com<\/a><\/p>\n<p class=\"u-align-center u-custom-font u-font-montserrat u-text u-text-custom-color-4 u-text-3\" style=\"text-align: center;\">Validit\u00e0: 14 Febbraio 2023<\/p>\n<p class=\"u-align-center u-custom-font u-font-playfair-display u-text u-text-custom-color-4 u-text-4\" style=\"text-align: center;\">Per la vostra cena romantica, il nostro Chef ha pensato ad uno speciale men\u00f9 di San Valentino<\/p>\n<p class=\"u-align-center u-custom-font u-font-montserrat u-text u-text-custom-color-4 u-text-5\" style=\"text-align: center;\">140 euro la coppia bevande incluse<\/p>\n<p style=\"text-align: center;\"><a class=\"u-border-2 u-border-active-custom-color-4 u-border-custom-color-2 u-btn u-button-style u-custom-font u-file-link u-font-montserrat u-hover-grey-30 u-none u-btn-2\" href=\"https:\/\/assets.nicepagecdn.com\/d7a34154\/4077017\/files\/oliveto-sul-lago-menu-san-valentino-2023.pdf\" target=\"_blank\" rel=\"noopener\">Men\u00f9<\/a><\/p>\n<\/div>\n<\/section>\n<section id=\"sec-1e49\" class=\"u-clearfix u-color-scheme-u10 u-color-style-multicolor-1 u-custom-color-2 u-section-5\"><\/section>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_raw_html el_class=&#8221;richiedinfo&#8221;]JTNDYSUyMGhyZWYlM0QlMjJtYWlsdG8lM0FpbmZvJTQwb2xpdmV0b3N1bGxhZ28uY29tJTIyJTNFJTBBUHJlbm90YSUzQyUyRmElM0U=[\/vc_raw_html][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;312&#8243; img_size=&#8221;600&#215;600&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text] Fuga per due Nel giorno pi\u00f9 romantico dell\u2019anno, la Country House Oliveto sul Lago \u00e8 la scelta perfetta per lasciarsi alle spalle la quotidianit\u00e0 per ritrovare l\u2019intesa di coppia. Immersi nella meravigliosa cornice dei colli bolognesi, potrete riprendervi il tempo per voi, tra natura e benessere.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text] L&#8217;esperienza include: Un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Offerte -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/index.php\/offerte\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Offerte -\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_raw_html el_class=&#8221;richiedinfo&#8221;]JTNDYSUyMGhyZWYlM0QlMjJtYWlsdG8lM0FpbmZvJTQwb2xpdmV0b3N1bGxhZ28uY29tJTIyJTNFJTBBUHJlbm90YSUzQyUyRmElM0U=[\/vc_raw_html][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;312&#8243; img_size=&#8221;600&#215;600&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text] Fuga per due Nel giorno pi\u00f9 romantico dell\u2019anno, la Country House Oliveto sul Lago \u00e8 la scelta perfetta per lasciarsi alle spalle la quotidianit\u00e0 per ritrovare l\u2019intesa di coppia. Immersi nella meravigliosa cornice dei colli bolognesi, potrete riprendervi il tempo per voi, tra natura e benessere.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text] L&#8217;esperienza include: Un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/index.php\/offerte\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-20T13:59:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/index.php\/offerte\/\",\"url\":\"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/index.php\/offerte\/\",\"name\":\"Offerte -\",\"isPartOf\":{\"@id\":\"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/#website\"},\"datePublished\":\"2023-02-20T13:39:56+00:00\",\"dateModified\":\"2023-02-20T13:59:14+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/index.php\/offerte\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/#website\",\"url\":\"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Offerte -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/index.php\/offerte\/","og_locale":"it_IT","og_type":"article","og_title":"Offerte -","og_description":"[vc_row][vc_column][vc_raw_html el_class=&#8221;richiedinfo&#8221;]JTNDYSUyMGhyZWYlM0QlMjJtYWlsdG8lM0FpbmZvJTQwb2xpdmV0b3N1bGxhZ28uY29tJTIyJTNFJTBBUHJlbm90YSUzQyUyRmElM0U=[\/vc_raw_html][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;312&#8243; img_size=&#8221;600&#215;600&#8243;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_column_text] Fuga per due Nel giorno pi\u00f9 romantico dell\u2019anno, la Country House Oliveto sul Lago \u00e8 la scelta perfetta per lasciarsi alle spalle la quotidianit\u00e0 per ritrovare l\u2019intesa di coppia. Immersi nella meravigliosa cornice dei colli bolognesi, potrete riprendervi il tempo per voi, tra natura e benessere.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text] L&#8217;esperienza include: Un [&hellip;]","og_url":"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/index.php\/offerte\/","article_modified_time":"2023-02-20T13:59:14+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/index.php\/offerte\/","url":"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/index.php\/offerte\/","name":"Offerte -","isPartOf":{"@id":"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/#website"},"datePublished":"2023-02-20T13:39:56+00:00","dateModified":"2023-02-20T13:59:14+00:00","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/index.php\/offerte\/"]}]},{"@type":"WebSite","@id":"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/#website","url":"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/index.php\/wp-json\/wp\/v2\/pages\/310"}],"collection":[{"href":"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/index.php\/wp-json\/wp\/v2\/comments?post=310"}],"version-history":[{"count":5,"href":"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/index.php\/wp-json\/wp\/v2\/pages\/310\/revisions"}],"predecessor-version":[{"id":320,"href":"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/index.php\/wp-json\/wp\/v2\/pages\/310\/revisions\/320"}],"wp:attachment":[{"href":"http:\/\/sleepy-dhawan.77-81-228-88.plesk.page\/index.php\/wp-json\/wp\/v2\/media?parent=310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}